{"id":1455,"date":"2024-12-07T14:10:48","date_gmt":"2024-12-07T14:10:48","guid":{"rendered":"https:\/\/www.monique-peres.com\/accueil\/"},"modified":"2024-12-11T14:40:56","modified_gmt":"2024-12-11T14:40:56","slug":"accueil","status":"publish","type":"page","link":"https:\/\/www.monique-peres.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1455\" class=\"elementor elementor-1455 elementor-13\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96984ea e-con-full animated-fast e-flex elementor-invisible e-con e-parent\" data-id=\"96984ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c14cefd e-flex e-con-boxed e-con e-child\" data-id=\"c14cefd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9caacdd elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-fixed elementor-hidden-desktop elementor-widget elementor-widget-ucaddon_fullscreen_navigation_menu\" data-id=\"9caacdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;}\" data-widget_type=\"ucaddon_fullscreen_navigation_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Fullscreen Menu -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.monique-peres.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.monique-peres.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Fullscreen Menu *\/\n\n.elementor-sticky{\n\toverflow: visible !important;\n}\n\n\n  body.menu-opened,\n  html.menu-opened{\n  \toverflow: hidden;\n  }\t \n\t\n\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd * {\n  box-sizing: border-box;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd a,\n#uc_fullscreen_navigation_menu_elementor_9caacdd a:visited,\n#uc_fullscreen_navigation_menu_elementor_9caacdd a:hover,\n#uc_fullscreen_navigation_menu_elementor_9caacdd a:active {\n  text-decoration: none;\n}\n\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue-input-wrapper\n{\n  position:relative;\n  \n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue-input-wrapper-align{\n  display:flex;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger *{\n  transition: all 200ms;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger_custom_open svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger_custom_close svg\n{\n  height:1em;\n  width:1em;\n}\n\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd\n{\n  position:relative;\n  z-index:99998;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle {\n  position: absolute;\n  z-index: 100000000;\n  cursor: pointer;\n  opacity: 0;\n  top:0px;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked + .ue_hamburger > div:after {\n  opacity: 0;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd.menu-opened .ue_menu {\n  pointer-events: auto;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd.menu-opened .ue_menu > div.ue_inner_menu {\n      visibility: visible;\n  -webkit-transition-duration: 0.75s;\n          transition-duration: 0.75s;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd.menu-opened .ue_menu > div.ue_inner_menu > div > div {\n  opacity: 1;\n  transition: opacity 0.4s ease 0.4s;\n}\n\n\/* start open transition animations *\/\n\t\n\n\t\n\n\t\n\n\t\n\n\t\n\n\t\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu .ue_inner_menu {\ntransform: translate(0, -100%);\n  opacity: 0;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd.menu-opened .ue_menu > div.ue_inner_menu {\n  opacity: 1;\n  transition: opacity .7s ease, transform .7s ease;\n  -webkit-transform: translate(0, 0);\n          transform: translate(0, 0);\n}\n\t\n\n\t\n\n\t\n\/* end open transition animations *\/\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger {\n  top: 0;\n  cursor: pointer;\n  transition: 0.4s;\n  backface-visibility: hidden;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  position:absolute;\n  z-index:99999999;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked + .ue_hamburger > div {\n          transform: rotate(135deg);\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked + .ue_hamburger > div:before,\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked + .ue_hamburger > div:after {\n  top: 0;\n  -webkit-transform: rotate(90deg);\n          transform: rotate(90deg);\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked:hover + .ue_hamburger > div {\n          transform: rotate(225deg);\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div {\n  position: relative;\n  -webkit-box-flex: 0;\n          flex: none;\n  width: 100%;\n  height: 2px;\n  transition: all 0.4s ease;\n  display: flex;\n          align-items: center;\n          justify-content: center;\n  background-color:#ffffff;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .checkbox-toggle:checked + .ue_hamburger > div {\n          color:#ffffff;\n          background-color:;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd input:hover + .ue_hamburger > div\n{\n  background-color:#ffffff;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div:before,\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div:after {\n  content: '';\n  position: absolute;\n  z-index: 1;\n  top: -10px;\n  left: 0;\n  width: 100%;\n  height: 2px;\n  background: inherit;\n}\n\t\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div:after {\n  top: 10px;\n}\n\n\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu {\n  position: fixed;\n  top: 0;\n  left: 0;\n  width: 100%;\n  pointer-events: none;\n  visibility: hidden;       \n  backface-visibility: hidden;\n  outline: none;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n\/* start protection from doubled fixed section in elementor *\/\n.uc-hidden #uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu{\n   opacity: 0;\n   pointer-events: none;\n}\n.uc-visible #uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu{\n   opacity: 1;\n   pointer-events: all;\n}\n\/* end protection from doubled fixed section in elementor *\/\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu .ue_inner_menu {\n  color: #fff;\n  transition: all 0.4s ease;\n  height: 100vh;\n  overflow-y: auto;\n  overflow-x: hidden;\n  display: flex;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_inner_menu-box{\n    margin-top: auto;\n  \t\n  margin-bottom: auto;\n  width: 100vw;\n  flex: none;\n  backface-visibility: hidden;\n  display: flex;\n  flex-direction: column;\n  align-items: center;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu > div > div > div {\n  max-width: 90vw;\n  width: 100%;\n  opacity: 0;\n  -webkit-transition: opacity 0.4s ease;\n  transition: opacity 0.4s ease;\n  overflow-y: auto;\n  flex: none;\n  display: flex;\n  align-items: center;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd ul:not(#uc_fullscreen_navigation_menu_elementor_9caacdd section ul) {\n  list-style: none;\n  margin: 0;\n  display: block;\n  padding:0px;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu  div  div  ul li {\n  padding: 0;\n  display: block;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu  div  div  ul  li a {\n  position: relative;\n  display: inline-flex;\n  align-items: center;\n  cursor: pointer;\n  transition: color 0.4s ease;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu  div  div  ul  li  a:hover {\n}\n\n\n\n\n\t\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu  div  div  ul  li a:hover:after {\n  width: 100%;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu  div  div  ul  li  a:after {\n  content: '';\n  position: absolute;\n  z-index: 1;\n  bottom: 0;\n  left: 0;\n  width: 0;\n  height: 2px;\n  transition: width 0.4s ease;\n}\n\n\t\n\n\n\n.ue_menu_wrapper\n{\n  position:relative;\n}\n\n\n\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu-social-icons a\n{\n  display:inline-block;\n  line-height:1em;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_menu-social-icons a svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .sub-menu\n{\ntransition: 0.5s;\noverflow: hidden;\nheight: auto;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .collapsed i::before,\n#uc_fullscreen_navigation_menu_elementor_9caacdd .expanded i::before{\n    font-weight: 900;\n  \tfont-size: 14px;\n    line-height:1em;\n  \tdisplay: inline-block;\n    vertical-align: middle;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd .uc-menu-item-pointer{\n  \tposition: absolute;\n  \tpointer-events: all;\n           right: -15px;\n  \t   transform: translate(14px,0);\n    }\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .uc-menu-item-pointer > *{\n  pointer-events: none;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .uc-menu-item-pointer svg{\n\twidth: 14px;\n  \theight: 14px;\n}\n\n#uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div, #uc_fullscreen_navigation_menu_elementor_9caacdd .ue_hamburger > div:before, #uc_fullscreen_navigation_menu_elementor_9caacdd  .ue_hamburger > div:after{\n outline: 0px solid #ffffff;\n}\n#uc_fullscreen_navigation_menu_elementor_9caacdd input:hover + .ue_hamburger > div, #uc_fullscreen_navigation_menu_elementor_9caacdd input:hover + .ue_hamburger > div:before, #uc_fullscreen_navigation_menu_elementor_9caacdd input:hover + .ue_hamburger > div:after{\n outline: 0px solid #ffffff;\n}\n\n\n<\/style>\n\n<div class=\"outer-menu\" id=\"uc_fullscreen_navigation_menu_elementor_9caacdd\">\n  \n  <div class=\"ue_menu_wrapper\">\n    <div class=\"ue-input-wrapper-align\">\n    <div class=\"ue-input-wrapper\">\n    <input id=\"uc_fullscreen_navigation_menu_elementor_9caacdd_input\" name=\"fullscreen_menu_input\" class=\"checkbox-toggle\" type=\"checkbox\" \/>\n   \n    \n    <div class=\"ue_hamburger\">\n      <div>\n\n          \t\n\n      <\/div>\n    <\/div>\n    <\/div>\n    <\/div>\n  \n    <div class=\"ue_menu\">\n\n      <div class=\"ue_inner_menu\" data-closeothers=\"no\" data-clickable='false' data-icon-position=\"end\" data-icon-source=\"\" data-expand>\n\n                \t<div class=\"ue_inner_menu_expand_icon\" style=\"display: none\"><i class='fas fa-arrow-down'><\/i><\/div>\n        \t<div class=\"ue_inner_menu_collapse_icon\" style=\"display: none\"><i class='fas fa-arrow-up'><\/i><\/div>\n        \t\n        \n        <div class=\"ue_inner_menu-box\">\n\n          <div><\/div>\n\n          \t\n\n          <div>\n            <ul id=\"menu-menu-principal\" class=\"uc-list-menu\"><li id=\"menu-item-1457\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1457\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\">Accueil<\/a><\/li>\n<li id=\"menu-item-1422\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1422\"><a href=\"https:\/\/www.monique-peres.com\/fr\/about\/\">A propos<\/a><\/li>\n<li id=\"menu-item-1452\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1452\"><a href=\"https:\/\/www.monique-peres.com\/fr\/tattoos\/\">Tattoos<\/a><\/li>\n<li id=\"menu-item-1443\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1443\"><a href=\"https:\/\/www.monique-peres.com\/fr\/peintures\/\">Peintures<\/a><\/li>\n<li id=\"menu-item-1510\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1510\"><a href=\"https:\/\/www.monique-peres.com\/fr\/boutique\/\">Boutique<\/a><\/li>\n<li id=\"menu-item-1460\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1460\"><a href=\"https:\/\/www.monique-peres.com\/fr\/contact\/\">Contact<\/a><\/li>\n<li id=\"menu-item-wpml-ls-45-fr\" class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-45-fr\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-45-fr\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"Fran\u00e7ais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-wpml-ls-45-en\" class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-en\"><a href=\"https:\/\/www.monique-peres.com\/\" title=\"Passer \u00e0 Anglais\" aria-label=\"Passer \u00e0 Anglais\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Anglais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li id=\"menu-item-wpml-ls-45-pt-br\" class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-pt-br wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-pt-br\"><a href=\"https:\/\/www.monique-peres.com\/pt-br\/\" title=\"Passer \u00e0 Portugais - du Br\u00e9sil\" aria-label=\"Passer \u00e0 Portugais - du Br\u00e9sil\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-br.svg\"\n            alt=\"Portugais - du Br\u00e9sil\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li id=\"menu-item-wpml-ls-45-es\" class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-es\"><a href=\"https:\/\/www.monique-peres.com\/es\/\" title=\"Passer \u00e0 Espagnol\" aria-label=\"Passer \u00e0 Espagnol\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"Espagnol\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n          <\/div>\n\n\n                        <div class=\"ue_menu-social-icons\">\n                      <a class=\"\" href=\"https:\/\/www.facebook.com\/moniqueperess\/\"  target='_blank'>\n\t<i class='fab fa-facebook'><\/i>\n<\/a>\n<a class=\"\" href=\"https:\/\/www.instagram.com\/moniqueperes\/\"  target='_blank'>\n\t<i class='fab fa-instagram'><\/i>\n<\/a>\n\n                <\/div> \n          \t\n\n          <div><\/div>\n\n        <\/div>\n\n      <\/div>\n    <\/div>\n  \n  <\/div>\n<\/div>\n<!-- end Fullscreen Menu -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dcfee6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-nav-menu\" data-id=\"9dcfee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-9dcfee6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1457\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\" class=\"elementor-item\">Accueil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1422\"><a href=\"https:\/\/www.monique-peres.com\/fr\/about\/\" class=\"elementor-item\">A propos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1452\"><a href=\"https:\/\/www.monique-peres.com\/fr\/tattoos\/\" class=\"elementor-item\">Tattoos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1443\"><a href=\"https:\/\/www.monique-peres.com\/fr\/peintures\/\" class=\"elementor-item\">Peintures<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1510\"><a href=\"https:\/\/www.monique-peres.com\/fr\/boutique\/\" class=\"elementor-item\">Boutique<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1460\"><a href=\"https:\/\/www.monique-peres.com\/fr\/contact\/\" class=\"elementor-item\">Contact<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-45-fr\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-45-fr\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"Fran\u00e7ais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-en\"><a href=\"https:\/\/www.monique-peres.com\/\" title=\"Passer \u00e0 Anglais\" aria-label=\"Passer \u00e0 Anglais\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Anglais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-pt-br wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-pt-br\"><a href=\"https:\/\/www.monique-peres.com\/pt-br\/\" title=\"Passer \u00e0 Portugais - du Br\u00e9sil\" aria-label=\"Passer \u00e0 Portugais - du Br\u00e9sil\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-br.svg\"\n            alt=\"Portugais - du Br\u00e9sil\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-es\"><a href=\"https:\/\/www.monique-peres.com\/es\/\" title=\"Passer \u00e0 Espagnol\" aria-label=\"Passer \u00e0 Espagnol\" class=\"elementor-sub-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"Espagnol\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-9dcfee6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1457\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\" class=\"elementor-item\" tabindex=\"-1\">Accueil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1422\"><a href=\"https:\/\/www.monique-peres.com\/fr\/about\/\" class=\"elementor-item\" tabindex=\"-1\">A propos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1452\"><a href=\"https:\/\/www.monique-peres.com\/fr\/tattoos\/\" class=\"elementor-item\" tabindex=\"-1\">Tattoos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1443\"><a href=\"https:\/\/www.monique-peres.com\/fr\/peintures\/\" class=\"elementor-item\" tabindex=\"-1\">Peintures<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1510\"><a href=\"https:\/\/www.monique-peres.com\/fr\/boutique\/\" class=\"elementor-item\" tabindex=\"-1\">Boutique<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1460\"><a href=\"https:\/\/www.monique-peres.com\/fr\/contact\/\" class=\"elementor-item\" tabindex=\"-1\">Contact<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-45-fr\"><a href=\"https:\/\/www.monique-peres.com\/fr\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-45-fr\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"Fran\u00e7ais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-en\"><a href=\"https:\/\/www.monique-peres.com\/\" title=\"Passer \u00e0 Anglais\" aria-label=\"Passer \u00e0 Anglais\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Anglais\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-pt-br wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-pt-br\"><a href=\"https:\/\/www.monique-peres.com\/pt-br\/\" title=\"Passer \u00e0 Portugais - du Br\u00e9sil\" aria-label=\"Passer \u00e0 Portugais - du Br\u00e9sil\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-br.svg\"\n            alt=\"Portugais - du Br\u00e9sil\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-45 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-45-es\"><a href=\"https:\/\/www.monique-peres.com\/es\/\" title=\"Passer \u00e0 Espagnol\" aria-label=\"Passer \u00e0 Espagnol\" class=\"elementor-sub-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.monique-peres.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"Espagnol\"\n            loading=\"lazy\"\n            width=20\n            \n    \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-869920f e-con-full e-flex e-con e-child\" data-id=\"869920f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eae4f6 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2eae4f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Monique Peres<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9aa919 animated-fast elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"b9aa919\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c0f8a animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"44c0f8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Artiste Tatoueuse - Peintre<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home About Tattoos Paintings Shop Contact Monique Peres Artiste Tatoueuse &#8211; Peintre<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-1455","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - Monique Peres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monique-peres.com\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - Monique Peres\" \/>\n<meta property=\"og:description\" content=\"Home About Tattoos Paintings Shop Contact Monique Peres Artiste Tatoueuse &#8211; Peintre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monique-peres.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Monique Peres\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-11T14:40:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monique-peres.com\\\/\",\"url\":\"https:\\\/\\\/www.monique-peres.com\\\/\",\"name\":\"Accueil - Monique Peres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monique-peres.com\\\/#website\"},\"datePublished\":\"2024-12-07T14:10:48+00:00\",\"dateModified\":\"2024-12-11T14:40:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monique-peres.com\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monique-peres.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monique-peres.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.monique-peres.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monique-peres.com\\\/#website\",\"url\":\"https:\\\/\\\/www.monique-peres.com\\\/\",\"name\":\"Monique Peres\",\"description\":\"Tattoo Artist - Painter\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monique-peres.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Monique Peres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monique-peres.com\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - Monique Peres","og_description":"Home About Tattoos Paintings Shop Contact Monique Peres Artiste Tatoueuse &#8211; Peintre","og_url":"https:\/\/www.monique-peres.com\/","og_site_name":"Monique Peres","article_modified_time":"2024-12-11T14:40:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monique-peres.com\/","url":"https:\/\/www.monique-peres.com\/","name":"Accueil - Monique Peres","isPartOf":{"@id":"https:\/\/www.monique-peres.com\/#website"},"datePublished":"2024-12-07T14:10:48+00:00","dateModified":"2024-12-11T14:40:56+00:00","breadcrumb":{"@id":"https:\/\/www.monique-peres.com\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monique-peres.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.monique-peres.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.monique-peres.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/www.monique-peres.com\/#website","url":"https:\/\/www.monique-peres.com\/","name":"Monique Peres","description":"Tattoo Artist - Painter","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monique-peres.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/pages\/1455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/comments?post=1455"}],"version-history":[{"count":7,"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/pages\/1455\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/pages\/1455\/revisions\/1616"}],"wp:attachment":[{"href":"https:\/\/www.monique-peres.com\/fr\/wp-json\/wp\/v2\/media?parent=1455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}